{"id":6162,"date":"2025-08-20T15:58:41","date_gmt":"2025-08-20T13:58:41","guid":{"rendered":"https:\/\/www.productip.com\/sicherheit-datenschutz\/"},"modified":"2026-05-07T13:26:07","modified_gmt":"2026-05-07T11:26:07","slug":"sicherheit-datenschutz","status":"publish","type":"page","link":"https:\/\/www.productip.com\/de\/sicherheit-datenschutz\/","title":{"rendered":"Sicherheit &#038; Datenschutz"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"6162\" class=\"elementor elementor-6162 elementor-2068\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f35902c e-con-full pf-hero e-flex e-con e-parent\" data-id=\"f35902c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-0ec58ed e-con-full hero-img e-flex e-con e-child\" data-id=\"0ec58ed\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-36bad39 elementor-widget elementor-widget-image\" data-id=\"36bad39\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"960\" height=\"412\" src=\"https:\/\/www.productip.com\/wp-content\/uploads\/Background-1.jpg\" class=\"attachment-full size-full wp-image-9050\" alt=\"Sicherheit &amp; Datenschutz\" srcset=\"https:\/\/www.productip.com\/wp-content\/uploads\/Background-1.jpg 960w, https:\/\/www.productip.com\/wp-content\/uploads\/Background-1-300x129.jpg 300w, https:\/\/www.productip.com\/wp-content\/uploads\/Background-1-768x330.jpg 768w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-28e6902 pf-text-container e-flex e-con-boxed e-con e-child\" data-id=\"28e6902\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;position&quot;:&quot;absolute&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-351e8a5 e-con-full pf-content-container e-flex e-con e-child\" data-id=\"351e8a5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eb89f3e pf-heading-h1 elementor-widget elementor-widget-heading\" data-id=\"eb89f3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Sicherheit &amp; Datenschutz<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33cb3bd elementor-widget__width-initial pf-paragraph elementor-widget elementor-widget-text-editor\" data-id=\"33cb3bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ernst gemeinte Product Compliance beginnt damit, dass Sicherheit und Datenschutz ernst genommen werden. Unsere Infrastrukturen und Prozesse entsprechen den h\u00f6chsten Sicherheits- und Datenschutzstandards.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2aa9cfe btn orange elementor-widget elementor-widget-button\" data-id=\"2aa9cfe\" data-element_type=\"widget\" data-e-type=\"widget\" data-text=\"Start today\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#read\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Weiterlesen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c63921 e-flex e-con-boxed e-con e-parent\" data-id=\"4c63921\" data-element_type=\"container\" data-e-type=\"container\" id=\"read\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b02d181 elementor-widget elementor-widget-spacer\" data-id=\"b02d181\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b077f69 e-flex e-con-boxed e-con e-parent\" data-id=\"b077f69\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3c8a494 e-con-full e-flex e-con e-child\" data-id=\"3c8a494\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c6d9609 e-con-full e-flex e-con e-child\" data-id=\"c6d9609\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2fd457a subheading elementor-widget elementor-widget-heading\" data-id=\"2fd457a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Datensicherheit ernst nehmen<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-244aff9 elementor-widget elementor-widget-heading\" data-id=\"244aff9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wir sind der Datensicherheit verpflichtet <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-51baf0b elementor-widget elementor-widget-text-editor\" data-id=\"51baf0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bei ProductIP besitzt die Datensicherheit h\u00f6chste Priorit\u00e4t. <br \/>Unsere Infrastruktur entspricht den h\u00f6chsten Standards und gew\u00e4hrleistet verschl\u00fcsselte Speicherung, sichere Authentifizierung und die Einhaltung von ISO 27001.<br \/>Wir sch\u00fctzen Ihre Informationen durch fortschrittlichen Schutz, kontinuierliche \u00dcberwachung und strenge Zugangskontrollen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9518558 e-con-full e-flex e-con e-child\" data-id=\"9518558\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-89dc94c elementor-widget elementor-widget-image\" data-id=\"89dc94c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"708\" height=\"432\" src=\"https:\/\/www.productip.com\/wp-content\/uploads\/Frame-2147229070-1.jpg\" class=\"attachment-large size-large wp-image-9051\" alt=\"Datensicherheit ernst nehmen\" srcset=\"https:\/\/www.productip.com\/wp-content\/uploads\/Frame-2147229070-1.jpg 708w, https:\/\/www.productip.com\/wp-content\/uploads\/Frame-2147229070-1-300x183.jpg 300w\" sizes=\"(max-width: 708px) 100vw, 708px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-163a6a0 e-grid e-con-boxed e-con e-parent\" data-id=\"163a6a0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e2cc2dd e-con-full e-flex e-con e-child\" data-id=\"e2cc2dd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5506a3b elementor-widget elementor-widget-heading\" data-id=\"5506a3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Mehrere Rechenzentren<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ffcb02c elementor-widget elementor-widget-text-editor\" data-id=\"ffcb02c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>ProductIP l\u00e4uft auf virtuellen Servern in sicheren Rechenzentren in Eemshaven (Niederlande) und Tokio (Japan). Diese Rechenzentren bieten dank redundanter Netzwerke ein Servicelevelziel von 99,99 % Netzwerkverf\u00fcgbarkeit.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bcb1784 e-con-full e-flex e-con e-child\" data-id=\"bcb1784\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1aa75f1 elementor-widget elementor-widget-heading\" data-id=\"1aa75f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Sichere Server<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-340f340 elementor-widget elementor-widget-text-editor\" data-id=\"340f340\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Server sind durch fortschrittliche Sicherheitssoftware und Firewalls gesch\u00fctzt. Alle Daten werden in verschl\u00fcsselter Form gespeichert und die Informationen werden automatisch zwischen den Servern synchronisiert. Die Kommunikation zwischen den Servern erfolgt vollst\u00e4ndig verschl\u00fcsselt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-347a95c e-con-full e-flex e-con e-child\" data-id=\"347a95c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-63bcbd2 elementor-widget elementor-widget-heading\" data-id=\"63bcbd2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Kontrollierter Benutzerzugang <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb5c1c3 elementor-widget elementor-widget-text-editor\" data-id=\"bb5c1c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>ProductIP bietet autorisierten Benutzern einen sicheren Zugang \u00fcber eine einstufige oder zweistufige Authentifizierung. Die Verwaltung von Benutzerrechten und -beschr\u00e4nkungen ist in Ihrem Unternehmenskonto m\u00f6glich. Dadurch kann kontrolliert werden, wer Zugriff auf bestimmte Daten und Funktionen innerhalb des Systems hat.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ec6637d e-con-full e-flex e-con e-child\" data-id=\"ec6637d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a376951 elementor-widget elementor-widget-heading\" data-id=\"a376951\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Einmalanmeldung (Single Sign-on, SSO)<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-832fafc elementor-widget elementor-widget-text-editor\" data-id=\"832fafc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bei einigen Angeboten bietet ProductIP die Option der Einmalanmeldung (Single Sign-On, SSO) an, die zus\u00e4tzlichen Komfort und noch mehr Sicherheit bietet. Bitte beachten Sie, dass dies mit zus\u00e4tzlichen Einrichtungskosten verbunden sein kann.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7ccfb7a e-con-full e-flex e-con e-child\" data-id=\"7ccfb7a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9006d03 elementor-widget elementor-widget-heading\" data-id=\"9006d03\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">ISO 27001-zertifiziert<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-814923c elementor-widget elementor-widget-text-editor\" data-id=\"814923c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>ProductIP ist vom T\u00dcV NORD Niederlande ISO 27001-zertifiziert, wodurch garantiert wird, dass unser Informationssicherheitssystem den internationalen Standards f\u00fcr Informationssicherheit entspricht.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6e7f7dc e-con-full e-flex e-con e-child\" data-id=\"6e7f7dc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eac503f elementor-widget elementor-widget-heading\" data-id=\"eac503f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">DSGVO-konform <\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ddc67e9 elementor-widget elementor-widget-text-editor\" data-id=\"ddc67e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Einhaltung der Datenschutz-Grundverordnung (DSGVO) wird in der Datenschutzerkl\u00e4rung behandelt, die Sie auf unserer Datenschutzseite finden. <a href=\"https:\/\/privacy.productip.com\/dpa\">\u00dcber diese URL<\/a> kann auch eine Datenverarbeitungsvereinbarung erstellt werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e1a0057 e-flex e-con-boxed e-con e-parent\" data-id=\"e1a0057\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4476ca1 e-con-full e-flex e-con e-child\" data-id=\"4476ca1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d134dd8 elementor-widget elementor-widget-image\" data-id=\"d134dd8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"531\" height=\"377\" src=\"https:\/\/www.productip.com\/wp-content\/uploads\/Rectangle-5460.jpg\" class=\"attachment-large size-large wp-image-9052\" alt=\"Erkl\u00e4rungen &amp; Vereinbarungen\" srcset=\"https:\/\/www.productip.com\/wp-content\/uploads\/Rectangle-5460.jpg 531w, https:\/\/www.productip.com\/wp-content\/uploads\/Rectangle-5460-300x213.jpg 300w\" sizes=\"(max-width: 531px) 100vw, 531px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-00a5683 e-con-full e-flex e-con e-child\" data-id=\"00a5683\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b7a586a e-con-full e-flex e-con e-child\" data-id=\"b7a586a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1fb4642 elementor-widget elementor-widget-heading\" data-id=\"1fb4642\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Erkl\u00e4rungen &amp; Vereinbarungen <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2caa4db elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2caa4db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.productip.com\/de\/cookie-erklaerung\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\"><g clip-path=\"url(#clip0_7953_22895)\"><path d=\"M-12.8248 44.8702L-4.74953 44.7499L-12.8248 44.8702ZM-4.74953 44.7499L-4.86981 52.8251L-4.74953 44.7499ZM-4.74953 44.7499L-15.2501 55.2504L-4.74953 44.7499Z\" fill=\"#F55522\"><\/path><path d=\"M-12.8248 44.8702L-4.74953 44.7499M-4.74953 44.7499L-4.86981 52.8251M-4.74953 44.7499L-15.2501 55.2504\" stroke=\"#F55522\" stroke-width=\"2\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M27.4028 15.5972L35.478 15.4769L27.4028 15.5972ZM35.478 15.4769L35.3577 23.5522L35.478 15.4769ZM35.478 15.4769L24.9775 25.9775L35.478 15.4769Z\" fill=\"#2D2D2D\"><\/path><path d=\"M27.4028 15.5972L35.478 15.4769M35.478 15.4769L35.3577 23.5522M35.478 15.4769L24.9775 25.9775\" stroke=\"#2D2D2D\" stroke-width=\"2\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/g><defs><clipPath id=\"clip0_7953_22895\"><rect width=\"40\" height=\"40\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cookie-Erkl\u00e4rung <\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.productip.com\/de\/datenschutzerklaerung\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\"><g clip-path=\"url(#clip0_7953_22895)\"><path d=\"M-12.8248 44.8702L-4.74953 44.7499L-12.8248 44.8702ZM-4.74953 44.7499L-4.86981 52.8251L-4.74953 44.7499ZM-4.74953 44.7499L-15.2501 55.2504L-4.74953 44.7499Z\" fill=\"#F55522\"><\/path><path d=\"M-12.8248 44.8702L-4.74953 44.7499M-4.74953 44.7499L-4.86981 52.8251M-4.74953 44.7499L-15.2501 55.2504\" stroke=\"#F55522\" stroke-width=\"2\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M27.4028 15.5972L35.478 15.4769L27.4028 15.5972ZM35.478 15.4769L35.3577 23.5522L35.478 15.4769ZM35.478 15.4769L24.9775 25.9775L35.478 15.4769Z\" fill=\"#2D2D2D\"><\/path><path d=\"M27.4028 15.5972L35.478 15.4769M35.478 15.4769L35.3577 23.5522M35.478 15.4769L24.9775 25.9775\" stroke=\"#2D2D2D\" stroke-width=\"2\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/g><defs><clipPath id=\"clip0_7953_22895\"><rect width=\"40\" height=\"40\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Datenschutzerkl\u00e4rung <\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.productip.com\/de\/allgemeine-informationen\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\"><g clip-path=\"url(#clip0_7953_22895)\"><path d=\"M-12.8248 44.8702L-4.74953 44.7499L-12.8248 44.8702ZM-4.74953 44.7499L-4.86981 52.8251L-4.74953 44.7499ZM-4.74953 44.7499L-15.2501 55.2504L-4.74953 44.7499Z\" fill=\"#F55522\"><\/path><path d=\"M-12.8248 44.8702L-4.74953 44.7499M-4.74953 44.7499L-4.86981 52.8251M-4.74953 44.7499L-15.2501 55.2504\" stroke=\"#F55522\" stroke-width=\"2\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M27.4028 15.5972L35.478 15.4769L27.4028 15.5972ZM35.478 15.4769L35.3577 23.5522L35.478 15.4769ZM35.478 15.4769L24.9775 25.9775L35.478 15.4769Z\" fill=\"#2D2D2D\"><\/path><path d=\"M27.4028 15.5972L35.478 15.4769M35.478 15.4769L35.3577 23.5522M35.478 15.4769L24.9775 25.9775\" stroke=\"#2D2D2D\" stroke-width=\"2\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/g><defs><clipPath id=\"clip0_7953_22895\"><rect width=\"40\" height=\"40\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Allgemeine Informationen <\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.productip.com\/wp-content\/general_conditions_productip.pdf\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\"><g clip-path=\"url(#clip0_7953_22895)\"><path d=\"M-12.8248 44.8702L-4.74953 44.7499L-12.8248 44.8702ZM-4.74953 44.7499L-4.86981 52.8251L-4.74953 44.7499ZM-4.74953 44.7499L-15.2501 55.2504L-4.74953 44.7499Z\" fill=\"#F55522\"><\/path><path d=\"M-12.8248 44.8702L-4.74953 44.7499M-4.74953 44.7499L-4.86981 52.8251M-4.74953 44.7499L-15.2501 55.2504\" stroke=\"#F55522\" stroke-width=\"2\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M27.4028 15.5972L35.478 15.4769L27.4028 15.5972ZM35.478 15.4769L35.3577 23.5522L35.478 15.4769ZM35.478 15.4769L24.9775 25.9775L35.478 15.4769Z\" fill=\"#2D2D2D\"><\/path><path d=\"M27.4028 15.5972L35.478 15.4769M35.478 15.4769L35.3577 23.5522M35.478 15.4769L24.9775 25.9775\" stroke=\"#2D2D2D\" stroke-width=\"2\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/g><defs><clipPath id=\"clip0_7953_22895\"><rect width=\"40\" height=\"40\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Allgemeine Bedingungen <\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.productip.com\/de\/nutzungsbedingungen\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\"><g clip-path=\"url(#clip0_7953_22895)\"><path d=\"M-12.8248 44.8702L-4.74953 44.7499L-12.8248 44.8702ZM-4.74953 44.7499L-4.86981 52.8251L-4.74953 44.7499ZM-4.74953 44.7499L-15.2501 55.2504L-4.74953 44.7499Z\" fill=\"#F55522\"><\/path><path d=\"M-12.8248 44.8702L-4.74953 44.7499M-4.74953 44.7499L-4.86981 52.8251M-4.74953 44.7499L-15.2501 55.2504\" stroke=\"#F55522\" stroke-width=\"2\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M27.4028 15.5972L35.478 15.4769L27.4028 15.5972ZM35.478 15.4769L35.3577 23.5522L35.478 15.4769ZM35.478 15.4769L24.9775 25.9775L35.478 15.4769Z\" fill=\"#2D2D2D\"><\/path><path d=\"M27.4028 15.5972L35.478 15.4769M35.478 15.4769L35.3577 23.5522M35.478 15.4769L24.9775 25.9775\" stroke=\"#2D2D2D\" stroke-width=\"2\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/g><defs><clipPath id=\"clip0_7953_22895\"><rect width=\"40\" height=\"40\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Nutzungsbedingungen <\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/privacy.productip.com\/dpa\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\"><g clip-path=\"url(#clip0_7953_22895)\"><path d=\"M-12.8248 44.8702L-4.74953 44.7499L-12.8248 44.8702ZM-4.74953 44.7499L-4.86981 52.8251L-4.74953 44.7499ZM-4.74953 44.7499L-15.2501 55.2504L-4.74953 44.7499Z\" fill=\"#F55522\"><\/path><path d=\"M-12.8248 44.8702L-4.74953 44.7499M-4.74953 44.7499L-4.86981 52.8251M-4.74953 44.7499L-15.2501 55.2504\" stroke=\"#F55522\" stroke-width=\"2\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M27.4028 15.5972L35.478 15.4769L27.4028 15.5972ZM35.478 15.4769L35.3577 23.5522L35.478 15.4769ZM35.478 15.4769L24.9775 25.9775L35.478 15.4769Z\" fill=\"#2D2D2D\"><\/path><path d=\"M27.4028 15.5972L35.478 15.4769M35.478 15.4769L35.3577 23.5522M35.478 15.4769L24.9775 25.9775\" stroke=\"#2D2D2D\" stroke-width=\"2\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/g><defs><clipPath id=\"clip0_7953_22895\"><rect width=\"40\" height=\"40\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Datenverarbeitungsvereinbarung<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e907f14 e-con-full e-flex e-con e-parent\" data-id=\"e907f14\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e21539a elementor-widget elementor-widget-template\" data-id=\"e21539a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"container\" data-elementor-id=\"6142\" class=\"elementor elementor-6142 elementor-1073 elementor-1073\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-13629869 e-flex e-con-boxed e-con e-parent\" data-id=\"13629869\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-3b54fd5c e-con-full e-flex e-con e-child\" data-id=\"3b54fd5c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-6ea22ce8 e-con-full e-flex e-con e-child\" data-id=\"6ea22ce8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-39b7967 subheading elementor-widget elementor-widget-heading\" data-id=\"39b7967\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Unternehmen Sie gleich den ersten Schritt!<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fd7d6e elementor-widget elementor-widget-heading\" data-id=\"7fd7d6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Abonnieren Sie den ProductIP-Newsletter. <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50291a1 elementor-widget elementor-widget-text-editor\" data-id=\"50291a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Erfahren Sie es zuerst \u2013 die neuesten regulatorischen Entwicklungen, die Plattformaktualisierungen sowie Details zu unseren Wissens- und Netzwerkveranstaltungen!<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7714ba4 elementor-widget elementor-widget-shortcode\" data-id=\"7714ba4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><script>\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n<\/script>\n\n                <div class='gf_browser_gecko gform_wrapper gravity-theme gform-theme--no-framework' data-form-theme='gravity-theme' data-form-index='0' id='gform_wrapper_8' ><div id='gf_8' class='gform_anchor' tabindex='-1'><\/div>\n                        <div class='gform_heading'>\n\t\t\t\t\t\t\t<p class='gform_required_legend'><\/p>\n                        <\/div><form method='post' enctype='multipart\/form-data' target='gform_ajax_frame_8' id='gform_8'  action='\/de\/wp-json\/wp\/v2\/pages\/6162#gf_8' data-formid='8' novalidate>\n                        <div class='gform-body gform_body'><div id='gform_fields_8' class='gform_fields top_label form_sublabel_below description_below validation_below'><div id=\"field_8_12\" class=\"gfield gfield--type-honeypot gform_validation_container field_sublabel_below gfield--has-description field_description_below field_validation_below gfield_visibility_visible\"  ><label class='gfield_label gform-field-label' for='input_8_12'>Comments<\/label><div class='ginput_container'><input name='input_12' id='input_8_12' type='text' value='' autocomplete='new-password'\/><\/div><div class='gfield_description' id='gfield_description_8_12'>Dieses Feld dient zur Validierung und sollte nicht ver\u00e4ndert werden.<\/div><\/div><div id=\"field_8_1\" class=\"gfield gfield--type-text gfield--input-type-text gfield--width-half gf_left_half gfield--width-half gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible active-label\"  data-field-class=\"active-label\" ><label class='gfield_label gform-field-label' for='input_8_1'>Vorname<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_text'><input name='input_1' id='input_8_1' type='text' value='' class='large'   tabindex='61'  aria-required=\"true\" aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_8_2\" class=\"gfield gfield--type-text gfield--input-type-text gfield--width-half gf_right_half gfield--width-half field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible active-label\"  data-field-class=\"active-label\" ><label class='gfield_label gform-field-label' for='input_8_2'>Nachname<\/label><div class='ginput_container ginput_container_text'><input name='input_2' id='input_8_2' type='text' value='' class='large'   tabindex='62'   aria-invalid=\"false\"   \/><\/div><\/div><div id=\"field_8_3\" class=\"gfield gfield--type-email gfield--input-type-email gfield--width-full gfield_contains_required field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible active-label\"  data-field-class=\"active-label\" ><label class='gfield_label gform-field-label' for='input_8_3'>E-Mail-Adresse<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/label><div class='ginput_container ginput_container_email'>\n                            <input name='input_3' id='input_8_3' type='email' value='' class='large' tabindex='63'   aria-required=\"true\" aria-invalid=\"false\"  \/>\n                        <\/div><\/div><fieldset id=\"field_8_10\" class=\"gfield gfield--type-consent gfield--type-choice gfield--input-type-consent gfield_contains_required field_sublabel_below gfield--no-description field_description_below hidden_label field_validation_below gfield_visibility_visible\"  ><legend class='gfield_label gform-field-label gfield_label_before_complex' >Zustimmung<span class=\"gfield_required\"><span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/span><\/legend><div class='ginput_container ginput_container_consent'><input name='input_10.1' id='input_8_10_1' type='checkbox' value='1' tabindex='64'  aria-required=\"true\" aria-invalid=\"false\"   \/> <label class=\"gform-field-label gform-field-label--type-inline gfield_consent_label\" for='input_8_10_1' >Ich akzeptiere die <a href=\"https:\/\/productip-de.dev.peakfort.nl\/datenschutzerklaerung\/\" target=\"_blank\">Datenschutzerkl\u00e4rung<\/a> und die <a href=\"\/wp-content\/uploads\/General_Conditions_ProductIP_Final_07_January_2015.pdf\" target=\"_blank\">allgemeinen Bedingungen<\/a>.<span class=\"gfield_required gfield_required_asterisk\">*<\/span><\/label><input type='hidden' name='input_10.2' value='Ich akzeptiere die &lt;a href=&quot;https:\/\/productip-de.dev.peakfort.nl\/datenschutzerklaerung\/&quot; target=&quot;_blank&quot;&gt;Datenschutzerkl\u00e4rung&lt;\/a&gt; und die &lt;a href=&quot;\/wp-content\/uploads\/General_Conditions_ProductIP_Final_07_January_2015.pdf&quot; target=&quot;_blank&quot;&gt;allgemeinen Bedingungen&lt;\/a&gt;.' class='gform_hidden' \/><input type='hidden' name='input_10.3' value='8' class='gform_hidden' \/><\/div><\/fieldset><div id=\"field_8_5\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_5' id='input_8_5' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_8_6\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_6' id='input_8_6' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_8_7\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_7' id='input_8_7' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_8_8\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_8' id='input_8_8' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='' \/><\/div><\/div><div id=\"field_8_11\" class=\"gfield gfield--type-hidden gfield--input-type-hidden gfield--width-full gform_hidden field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible\"  ><div class='ginput_container ginput_container_text'><input name='input_11' id='input_8_11' type='hidden' class='gform_hidden'  aria-invalid=\"false\" value='de' \/><\/div><\/div><\/div><\/div>\n        <div class='gform-footer gform_footer top_label'> <button id=\"gform_submit_button_8\" class=\"gform_button button btn gform-submit gform-submit-8\" type=\"submit\">\n            <span class=\"gform-btn-text\">Registrieren Sie sich<\/span>\n        <\/button> <input type='hidden' name='gform_ajax' value='form_id=8&amp;title=&amp;description=&amp;tabindex=61&amp;theme=gravity-theme&amp;styles=[]&amp;hash=76353f75282db131fc556b65ccafdd98' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submission_method' data-js='gform_submission_method_8' value='iframe' \/>\n            <input type='hidden' class='gform_hidden' name='gform_theme' data-js='gform_theme_8' id='gform_theme_8' value='gravity-theme' \/>\n            <input type='hidden' class='gform_hidden' name='gform_style_settings' data-js='gform_style_settings_8' id='gform_style_settings_8' value='[]' \/>\n            <input type='hidden' class='gform_hidden' name='is_submit_8' value='1' \/>\n            <input type='hidden' class='gform_hidden' name='gform_submit' value='8' \/>\n            \n            <input type='hidden' class='gform_hidden' name='gform_currency' data-currency='EUR' value='jfHozShQiLgiET4EuE+YQWuwHXPIjMnmy7yIEFnfPkOmjSCOiGYwegi+KoVU9Ipk66MIK4or0gypjk\/GWJzM+vMz3bRfmWG+LA1\/lrmiLEasrj0=' \/>\n            <input type='hidden' class='gform_hidden' name='gform_unique_id' value='' \/>\n            <input type='hidden' class='gform_hidden' name='state_8' value='WyJ7XCIxMC4xXCI6XCI2MGZhZWYxN2ExYzE4Nzg2ZWU4ODNmN2Q4NzYzMTk3MVwiLFwiMTAuMlwiOlwiYWRiMmUxNDE5YjljMmM2ODA2OTM2MWM1Mzc5YWI5ZGVcIixcIjEwLjNcIjpcIjVjY2M1N2FkODc2NmFhOTk3Y2MwYzdmYTFiYjg2N2NjXCJ9IiwiY2Y5MGVlNjllNjAwM2I3NWY2MWI3NGM1NGUxZmM3YTQiXQ==' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_target_page_number_8' id='gform_target_page_number_8' value='0' \/>\n            <input type='hidden' autocomplete='off' class='gform_hidden' name='gform_source_page_number_8' id='gform_source_page_number_8' value='1' \/>\n            <input type='hidden' name='gform_field_values' value='' \/>\n            \n        <\/div>\n                        <p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"ak_\"><label>&#916;<textarea name=\"ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"ak_js\" value=\"11\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><\/form>\n                        <\/div>\n\t\t                <iframe style='display:none;width:0px;height:0px;' src='about:blank' name='gform_ajax_frame_8' id='gform_ajax_frame_8' title='Dieser iframe enth\u00e4lt die erforderliche Logik um Gravity Forms Formulare mit AJAX zu handhaben.'><\/iframe>\n\t\t                <script>\ngform.initializeOnLoaded( function() {gformInitSpinner( 8, 'https:\/\/www.productip.com\/wp-content\/plugins\/cl-tune-hello\/img\/gformspinner.svg', true );jQuery('#gform_ajax_frame_8').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_8');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_8').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_8').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_8').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_8').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/ jQuery(document).scrollTop(jQuery('#gform_wrapper_8').offset().top - mt); }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_8').val();gformInitSpinner( 8, 'https:\/\/www.productip.com\/wp-content\/plugins\/cl-tune-hello\/img\/gformspinner.svg', true );jQuery(document).trigger('gform_page_loaded', [8, current_page]);window['gf_submitting_8'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_8').replaceWith(confirmation_content);jQuery(document).scrollTop(jQuery('#gf_8').offset().top - mt);jQuery(document).trigger('gform_confirmation_loaded', [8]);window['gf_submitting_8'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_8').text());}else{jQuery('#gform_8').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"8\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_8\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_8\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_8\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 8, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} );\n<\/script>\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d656b81 e-con-full e-flex e-con e-child\" data-id=\"d656b81\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-71cfff2 elementor-widget elementor-widget-image\" data-id=\"71cfff2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/www.productip.com\/wp-content\/uploads\/DSC09065-1024x683.jpg\" class=\"attachment-large size-large wp-image-8907\" alt=\"Newsletter cta\" srcset=\"https:\/\/www.productip.com\/wp-content\/uploads\/DSC09065-1024x683.jpg 1024w, https:\/\/www.productip.com\/wp-content\/uploads\/DSC09065-300x200.jpg 300w, https:\/\/www.productip.com\/wp-content\/uploads\/DSC09065-768x512.jpg 768w, https:\/\/www.productip.com\/wp-content\/uploads\/DSC09065-1536x1024.jpg 1536w, https:\/\/www.productip.com\/wp-content\/uploads\/DSC09065-2048x1365.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Sicherheit &amp; Datenschutz Ernst gemeinte Product Compliance beginnt damit, dass Sicherheit und Datenschutz ernst genommen werden. Unsere Infrastrukturen und Prozesse entsprechen den h\u00f6chsten Sicherheits- und Datenschutzstandards. Weiterlesen Datensicherheit ernst nehmen Wir sind der Datensicherheit verpflichtet Bei ProductIP besitzt die Datensicherheit h\u00f6chste Priorit\u00e4t. Unsere Infrastruktur entspricht den h\u00f6chsten Standards und gew\u00e4hrleistet verschl\u00fcsselte Speicherung, sichere Authentifizierung und [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6161,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-6162","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.productip.com\/de\/wp-json\/wp\/v2\/pages\/6162","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.productip.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.productip.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.productip.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.productip.com\/de\/wp-json\/wp\/v2\/comments?post=6162"}],"version-history":[{"count":26,"href":"https:\/\/www.productip.com\/de\/wp-json\/wp\/v2\/pages\/6162\/revisions"}],"predecessor-version":[{"id":9057,"href":"https:\/\/www.productip.com\/de\/wp-json\/wp\/v2\/pages\/6162\/revisions\/9057"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.productip.com\/de\/wp-json\/wp\/v2\/media\/6161"}],"wp:attachment":[{"href":"https:\/\/www.productip.com\/de\/wp-json\/wp\/v2\/media?parent=6162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}